{"id":284,"date":"2022-06-25T14:32:15","date_gmt":"2022-06-25T12:32:15","guid":{"rendered":"https:\/\/soundbelt.de\/?page_id=284"},"modified":"2022-09-08T13:42:43","modified_gmt":"2022-09-08T11:42:43","slug":"widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen","status":"publish","type":"page","link":"https:\/\/soundbelt.de\/en\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\/","title":{"rendered":"Right of withdrawal"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Widerrufsbelehrung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"\">Widerrufsrecht<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Waren in Besitz genommen haben bzw. hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns (Noah B\u00f6ker, 22527Hamburg,&nbsp;info@soundbelt.de, Telefon: 0152 58457219) mittels einer eindeutigen Erkl\u00e4rung (z. B. ein mit der Post versandter Brief, Telefax oder E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular verwenden, das jedoch nicht vorgeschrieben ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"\">Folgen des Widerrufs<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet.<br class=\"\">Wir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir die Waren wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie die Waren zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie haben die Waren unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrags unterrichten, an uns oder an<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noah B\u00f6ker<br>22527 Hamburg<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">zur\u00fcckzusenden oder zu \u00fcbergeben. Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der Frist von vierzehn Tagen absenden.<br class=\"\">Sie tragen die unmittelbaren Kosten der R\u00fccksendung der Waren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie m\u00fcssen f\u00fcr einen etwaigen Wertverlust der Waren nur aufkommen, wenn dieser Wertverlust auf einen zur Pr\u00fcfung der Beschaffenheit, Eigenschaften und Funktionsweise der Waren nicht notwendigen Umgang mit Ihnen zur\u00fcckzuf\u00fchren ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"\">Muster-Widerrufsformular<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(Wenn Sie den Vertrag widerrufen wollen, dann f\u00fcllen Sie bitte dieses Formular aus und senden Sie es zur\u00fcck.)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 An Noah B\u00f6ker, Jaguarstieg 28, 22527 Hamburg,&nbsp;info@soundbelt.de<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Hiermit widerrufe(n) ich\/wir (*) den von mir\/uns (*) abgeschlossenen Vertrag \u00fcber den Kauf der folgenden<br class=\"\">Waren (*)\/die Erbringung der folgenden Dienstleistung (*)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Bestellt am (*)\/erhalten am (*)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Name des\/der Verbraucher(s)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Anschrift des\/der Verbraucher(s)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Unterschrift des\/der Verbraucher(s) (nur bei Mitteilung auf Papier)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Datum<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*) Unzutreffendes streichen.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">R\u00fccksendungen<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die in diesem Abschnitt \u201cR\u00fccksendungen\u201d genannten Modalit\u00e4ten sind nicht Voraussetzung f\u00fcr die wirksame Aus\u00fcbung des Widerrufsrechts gem. dem Abschnitt \u201cWiderrufsrecht und Ausschluss des Widerrufs bei Verbrauchervertr\u00e4gen\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Verbraucher werden vor R\u00fccksendung gebeten, die R\u00fccksendung beim Verk\u00e4ufer zu melden [via&nbsp;info@soundbelt.de<a class=\"\" href=\"mailto:info@juststickit.de\"><\/a>], um die R\u00fccksendung anzuk\u00fcndigen. Auf diese Weise erm\u00f6glichen sie dem Verk\u00e4ufer eine schnellstm\u00f6gliche Zuordnung der Produkte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Verbraucher werden gebeten die Ware als frankiertes Paket an den Verk\u00e4ufer zur\u00fcck zu senden und den Einlieferbeleg aufzubewahren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Verbraucher werden gebeten Besch\u00e4digungen oder Verunreinigungen der Ware zu vermeiden. Die Ware sollte nach M\u00f6glichkeit in Originalverpackung mit s\u00e4mtlichem Zubeh\u00f6r an den Verk\u00e4ufer zur\u00fcck gesendet werden. Ist die Originalverpackung nicht mehr im Besitz des Verbrauchers, sollte eine andere geeigneten Verpackung verwendet werden, um f\u00fcr einen ausreichenden Schutz vor Transportsch\u00e4den zu sorgen und etwaige Schadensersatzanspr\u00fcche wegen Besch\u00e4digungen infolge mangelhafter Verpackung zu vermeiden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Widerrufsbelehrung Widerrufsrecht Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Waren in Besitz genommen haben bzw. hat. Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns (Noah&hellip;&nbsp;<a href=\"https:\/\/soundbelt.de\/en\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Right of withdrawal<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-284","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Widerrufsrecht und Ausschluss des Widerrufs bei Verbrauchervertr\u00e4gen - Soundbelt<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Widerrufsrecht und Ausschluss des Widerrufs bei Verbrauchervertr\u00e4gen - Soundbelt\" \/>\n<meta property=\"og:description\" content=\"Widerrufsbelehrung Widerrufsrecht Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Waren in Besitz genommen haben bzw. hat. Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns (Noah&hellip;&nbsp;Read More &raquo;Widerrufsrecht und Ausschluss des Widerrufs bei Verbrauchervertr\u00e4gen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soundbelt.de\/en\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\/\" \/>\n<meta property=\"og:site_name\" content=\"Soundbelt\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-08T11:42:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soundbelt.de\\\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\\\/\",\"url\":\"https:\\\/\\\/soundbelt.de\\\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\\\/\",\"name\":\"Widerrufsrecht und Ausschluss des Widerrufs bei Verbrauchervertr\u00e4gen - Soundbelt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soundbelt.de\\\/#website\"},\"datePublished\":\"2022-06-25T12:32:15+00:00\",\"dateModified\":\"2022-09-08T11:42:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soundbelt.de\\\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soundbelt.de\\\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soundbelt.de\\\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/soundbelt.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Widerrufsrecht und Ausschluss des Widerrufs bei Verbrauchervertr\u00e4gen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soundbelt.de\\\/#website\",\"url\":\"https:\\\/\\\/soundbelt.de\\\/\",\"name\":\"Soundbelt\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/soundbelt.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soundbelt.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soundbelt.de\\\/#organization\",\"name\":\"Soundbelt\",\"url\":\"https:\\\/\\\/soundbelt.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/soundbelt.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soundbelt.de\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Bildschirmfoto-2022-06-10-um-20.33.50-2.png\",\"contentUrl\":\"https:\\\/\\\/soundbelt.de\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Bildschirmfoto-2022-06-10-um-20.33.50-2.png\",\"width\":531,\"height\":350,\"caption\":\"Soundbelt\"},\"image\":{\"@id\":\"https:\\\/\\\/soundbelt.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/soundbelt.de\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Widerrufsrecht und Ausschluss des Widerrufs bei Verbrauchervertr\u00e4gen - Soundbelt","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_GB","og_type":"article","og_title":"Widerrufsrecht und Ausschluss des Widerrufs bei Verbrauchervertr\u00e4gen - Soundbelt","og_description":"Widerrufsbelehrung Widerrufsrecht Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Waren in Besitz genommen haben bzw. hat. Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns (Noah&hellip;&nbsp;Read More &raquo;Widerrufsrecht und Ausschluss des Widerrufs bei Verbrauchervertr\u00e4gen","og_url":"https:\/\/soundbelt.de\/en\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\/","og_site_name":"Soundbelt","article_modified_time":"2022-09-08T11:42:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soundbelt.de\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\/","url":"https:\/\/soundbelt.de\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\/","name":"Widerrufsrecht und Ausschluss des Widerrufs bei Verbrauchervertr\u00e4gen - Soundbelt","isPartOf":{"@id":"https:\/\/soundbelt.de\/#website"},"datePublished":"2022-06-25T12:32:15+00:00","dateModified":"2022-09-08T11:42:43+00:00","breadcrumb":{"@id":"https:\/\/soundbelt.de\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soundbelt.de\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soundbelt.de\/widerrufsrecht-und-ausschluss-des-widerrufs-bei-verbrauchervertraegen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/soundbelt.de\/"},{"@type":"ListItem","position":2,"name":"Widerrufsrecht und Ausschluss des Widerrufs bei Verbrauchervertr\u00e4gen"}]},{"@type":"WebSite","@id":"https:\/\/soundbelt.de\/#website","url":"https:\/\/soundbelt.de\/","name":"Soundbelt","description":"","publisher":{"@id":"https:\/\/soundbelt.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soundbelt.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/soundbelt.de\/#organization","name":"Soundbelt","url":"https:\/\/soundbelt.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/soundbelt.de\/#\/schema\/logo\/image\/","url":"https:\/\/soundbelt.de\/wp-content\/uploads\/2022\/06\/Bildschirmfoto-2022-06-10-um-20.33.50-2.png","contentUrl":"https:\/\/soundbelt.de\/wp-content\/uploads\/2022\/06\/Bildschirmfoto-2022-06-10-um-20.33.50-2.png","width":531,"height":350,"caption":"Soundbelt"},"image":{"@id":"https:\/\/soundbelt.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/soundbelt.de\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/soundbelt.de\/en\/wp-json\/wp\/v2\/pages\/284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soundbelt.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soundbelt.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soundbelt.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/soundbelt.de\/en\/wp-json\/wp\/v2\/comments?post=284"}],"version-history":[{"count":3,"href":"https:\/\/soundbelt.de\/en\/wp-json\/wp\/v2\/pages\/284\/revisions"}],"predecessor-version":[{"id":424,"href":"https:\/\/soundbelt.de\/en\/wp-json\/wp\/v2\/pages\/284\/revisions\/424"}],"wp:attachment":[{"href":"https:\/\/soundbelt.de\/en\/wp-json\/wp\/v2\/media?parent=284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}